{"id":105736,"date":"2021-09-28T00:00:00","date_gmt":"2021-09-27T14:00:00","guid":{"rendered":"https:\/\/revtrac2026.tempurl.host\/uncategorized\/shift-left-sap-aenderungsrisikos\/"},"modified":"2021-09-28T00:00:00","modified_gmt":"2021-09-27T14:00:00","slug":"shift-left-sap-aenderungsrisikos","status":"publish","type":"post","link":"https:\/\/rev-trac.com\/de\/artikel\/shift-left-sap-aenderungsrisikos\/","title":{"rendered":"Shift Left zur einfachen Reduzierung des SAP-\u00c4nderungsrisikos"},"content":{"rendered":"<p>Was ist eines der kritischeren Erfolgskriterien f\u00fcr SAP DevOps? Wenn Sie mit \u201eShift Left\u201c geantwortet haben, sind Sie auf dem richtigen Weg, Ihre DevOps-Ziele erfolgreich zu erreichen. <\/p>\n<p>Doch was bedeutet das Konzept von \u201e<a href=\"https:\/\/devopedia.org\/shift-left\">Shift Left<\/a>\u201c? Kann es wirklich dazu beitragen, das SAP-\u00c4nderungsrisiko zu reduzieren, das in den heutigen SAP-Umgebungen betr\u00e4chtlich ist? <\/p>\n<p>Shift Left ist ein Konzept, das dazu anregt, so viele Informationen und Erkenntnisse wie m\u00f6glich so fr\u00fch wie m\u00f6glich im Entwicklungszyklus zu gewinnen.<\/p>\n<p>Das bedeutet, dass alles \u2013 vom Design \u00fcber das Schreiben des Codes bis hin zum Testen \u2013 fr\u00fchzeitig im Prozess stattfindet. Dadurch werden Fehler fr\u00fcher entdeckt, die Anwendungsfunktionen entsprechen den Gesch\u00e4ftsanforderungen, und Aspekte der Sicherheit, Integration und Funktionalit\u00e4t werden fr\u00fcher gel\u00f6st. <\/p>\n<p>Letztendlich k\u00f6nnen Sie das SAP-\u00c4nderungsrisiko erheblich reduzieren, und SAP-IT-Teams k\u00f6nnen hochwertige SAP Changes in Gesch\u00e4ftsgeschwindigkeit bereitstellen. Der Schl\u00fcssel liegt darin zu verstehen, an welchen Objekten Programmierer arbeiten, und sicherzustellen, dass das Risiko entsprechend ber\u00fccksichtigt und kontrolliert wird. <\/p>\n<p><em>Wie kann Rev-Trac \u2013 eine automatisierte SAP-Change-Management-Plattform \u2013 das SAP-\u00c4nderungsrisiko, das t\u00e4glich durch technische Objekte entsteht, reduzieren?<\/em><\/p>\n<h3>Kritische und sensible Objekte<\/h3>\n<p>Viele Organisationen verf\u00fcgen \u00fcber Prozesse oder Tabellen, die f\u00fcr ihr t\u00e4gliches Gesch\u00e4ft kritisch oder sehr sensibel sind.<\/p>\n<p>Manchmal ist es notwendig, zus\u00e4tzliche Schritte, h\u00f6here Kontrollstufen oder autorisierte Genehmigungen einzuf\u00fchren, um die Bearbeitung dieser Objekte und deren Fortschritt durch eine SAP-Landschaft zu erm\u00f6glichen und das SAP-\u00c4nderungsrisiko zu reduzieren.<\/p>\n<p>Mit Rev-Trac k\u00f6nnen Kunden Objekte oder Objektbereiche definieren, die h\u00f6heren Compliance-Anforderungen unterliegen m\u00fcssen. Dies wird erzwungen, wenn Programmierer diese definierten sensiblen Objekte \u00e4ndern. <\/p>\n<h3>Parallel Development Workbench<\/h3>\n<p>Eines der riskantesten Unterfangen in der SAP-Anwendungsentwicklung ist, wenn zwei Programmierer parallel am selben Objekt arbeiten. Dies setzt Ihr Unternehmen einem falschen Transport-Sequencing und potenziellen Downgrades der Produktionsinstanz aus. <\/p>\n<blockquote>\n<p>Traditionelle SAP-Sperren k\u00f6nnen dazu beitragen, das SAP-\u00c4nderungsrisiko zu reduzieren, aber sobald der Transport freigegeben ist, k\u00f6nnen das Tempo und die Dringlichkeit jeder \u00c4nderung die Reihenfolge der Bereitstellung weiter<br \/>komplizieren.<\/p>\n<\/blockquote>\n<p>Die Verwendung von SAP Transport of Copies (TOCs) f\u00fcr Tests ist ein alternativer Ansatz, um die parallele Entwicklung besser zu verwalten und das SAP-\u00c4nderungsrisiko zu reduzieren.<\/p>\n<p>Dies funktioniert, indem die Sperre aufrechterhalten wird, bis die \u00c4nderung f\u00fcr die Bereitstellung in der Produktion bereit ist. Dies wirkt sich jedoch auf alle im Transport enthaltenen Objekte aus. Dies ist eine Herausforderung, wenn Notfallanpassungen an einzelnen Objekten erforderlich sind.  <\/p>\n<p>Im Gegensatz dazu erm\u00f6glicht das Advanced Locking System von Rev-Trac, dass die Sperre auf dem Objekt verbleibt, bis die \u00c4nderung in der Produktion angekommen ist.<\/p>\n<p>Die Parallel Development Workbench steuert dann, welche Objekte auf individueller Objektebene parallel entwickelt werden k\u00f6nnen.<\/p>\n<p>Da es auf individueller Objektebene arbeitet, werden nicht alle Objekte innerhalb eines Transports oder einer \u00c4nderung beeintr\u00e4chtigt.<\/p>\n<h3>Overtakes<\/h3>\n<p>Sobald die parallele Entwicklung genehmigt wurde, <strong>muss die korrekte Reihenfolge der Transporte verwaltet werden, da:<\/strong><\/p>\n<ol>\n<li>Unerw\u00fcnschte Objektmodifikationen unbeabsichtigt in eine nachfolgende Umgebung eingef\u00fchrt werden k\u00f6nnen; und<\/li>\n<li>Au\u00dferhalb der Reihenfolge liegende Migrationen oft zu einem sp\u00e4teren Zeitpunkt zu einem Downgrade f\u00fchren k\u00f6nnen.<\/li>\n<\/ol>\n<p>Das Overtake and Overwrite Protection System (OOPS) von Rev-Trac bietet mehrere Warnungen vor potenziellen Problemen. Ein Overtake (au\u00dferhalb der Reihenfolge) ist ein<br \/>Vorl\u00e4ufer eines potenziellen Overwrites (Downgrade). Ein Overwrite kann nicht erfolgen, es sei denn, eine \u00dcberholung wurde genehmigt.  <\/p>\n<p>Die OOPS-Warnungen geben den Benutzern, die an einer \u00c4nderungsanforderung arbeiten, Bewusstsein und Echtzeitkontrolle und bieten ihnen die M\u00f6glichkeit, zus\u00e4tzliche Risiken einzugehen.<\/p>\n<h3>CISS (Code Impact Scoring System)<\/h3>\n<p>CISS analysiert den Code in aufsteigender Richtung und entdeckt alle Programme oder Transaktionen und somit Prozesse, die ein ge\u00e4ndertes Objekt beeinflussen k\u00f6nnte.<\/p>\n<p><strong>Die Funktion:<\/strong><\/p>\n<ol>\n<li>Bietet Einblicke in Auswirkungen, die m\u00f6glicherweise nicht erkannt wurden und riskanter sein k\u00f6nnten als erwartet<\/li>\n<li>Vermittelt ein Verst\u00e4ndnis daf\u00fcr, welche Transaktionen, Programme oder Prozesse im Fokus der Tests stehen sollten.<\/li>\n<\/ol>\n<p>CISS bietet Echtzeit-Einblicke in die gr\u00f6\u00dferen Auswirkungen von \u00c4nderungen an SAP-Objekten. Dadurch kann das Risiko verstanden und verwaltet werden. <\/p>\n<h3>Fazit \u2013 Reduzieren Sie jetzt das SAP-\u00c4nderungsrisiko!<\/h3>\n<p>Benutzer eines automatisierten SAP-Change-Management-Systems m\u00fcssen mit geeigneten Risikomanagement- und Risikominderungstools ausgestattet werden.<\/p>\n<p>Dies stellt sicher, dass sie nicht nur auf die Risiken bei SAP Changes aufmerksam gemacht werden, sondern auch \u00fcber geeignete Kontrollen verf\u00fcgen, um die Risiken zu verwalten und zu \u00fcberwachen.<\/p>\n<p>Die erweiterten Funktionen von Rev-Trac unterst\u00fctzen den Shift Left, indem sie Benutzer warnen, bevor ein Problem entsteht, oder sicherstellen, dass sie sich der Risiken so fr\u00fch wie m\u00f6glich bewusst sind.<\/p>\n<p>F\u00fcr weitere Informationen, wie Sie das SAP-\u00c4nderungsrisiko reduzieren k\u00f6nnen, <a href=\"https:\/\/rev-trac.com\/de\/kontakt\/\">kontaktieren Sie bitte<\/a> einen unserer Change-Management-Experten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Letztendlich wird das Risiko erheblich reduziert, und SAP-IT-Teams k\u00f6nnen hochwertige SAP Changes in Gesch\u00e4ftsgeschwindigkeit bereitstellen.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"demo_duration":"","demo_product":"","demo_audience":"","demo_integrations":"","demo_url":"","demo_lede":"","webinar_type":"","webinar_status":"","webinar_date_display":"","webinar_date_start":"","webinar_time":"","webinar_duration":"","webinar_platform":"","webinar_presenter":"","webinar_video":"","agenda1_title":"","agenda1_desc":"","agenda2_title":"","agenda2_desc":"","agenda3_title":"","agenda3_desc":"","agenda4_title":"","agenda4_desc":"","agenda5_title":"","agenda5_desc":"","speaker1_name":"","speaker1_role":"","speaker1_photo":"","speaker2_name":"","speaker2_role":"","speaker2_photo":"","speaker3_name":"","speaker3_role":"","speaker3_photo":"","speaker4_name":"","speaker4_role":"","speaker4_photo":"","webinar_register":"","event_status":"","event_date_display":"","event_date_start":"","event_location":"","event_booth":"","event_format":"","event_url":"","session1_title":"","session1_speaker":"","session1_when":"","session1_room":"","session2_title":"","session2_speaker":"","session2_when":"","session2_room":"","session3_title":"","session3_speaker":"","session3_when":"","session3_room":"","session4_title":"","session4_speaker":"","session4_when":"","session4_room":"","team1_name":"","team1_role":"","team1_photo":"","team1_email":"","team1_linkedin":"","team2_name":"","team2_role":"","team2_photo":"","team2_email":"","team2_linkedin":"","team3_name":"","team3_role":"","team3_photo":"","team3_email":"","team3_linkedin":"","team4_name":"","team4_role":"","team4_photo":"","team4_email":"","team4_linkedin":"","team5_name":"","team5_role":"","team5_photo":"","team5_email":"","team5_linkedin":"","team6_name":"","team6_role":"","team6_photo":"","team6_email":"","team6_linkedin":"","event_booking":"","event_lede":"","cs_stat1_label":"","cs_stat1_value":"","cs_stat1_unit":"","cs_stat1_desc":"","cs_stat2_label":"","cs_stat2_value":"","cs_stat2_unit":"","cs_stat2_desc":"","cs_stat3_label":"","cs_stat3_value":"","cs_stat3_unit":"","cs_stat3_desc":"","cs_stat4_label":"","cs_stat4_value":"","cs_stat4_unit":"","cs_stat4_desc":"","cs_download_url":"","page_builder":"","footnotes":""},"categories":[159],"tags":[183],"class_list":["post-105736","post","type-post","status-publish","format-standard","hentry","category-artikel","tag-risikominderung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Shift Left zur einfachen Reduzierung des SAP-\u00c4nderungsrisikos - Rev-Trac<\/title>\n<meta name=\"description\" content=\"Letztendlich wird das Risiko erheblich reduziert, und SAP-IT-Teams k\u00f6nnen hochwertige SAP Changes in Gesch\u00e4ftsgeschwindigkeit bereitstellen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rev-trac.com\/de\/artikel\/shift-left-sap-aenderungsrisikos\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Shift Left zur einfachen Reduzierung des SAP-\u00c4nderungsrisikos\" \/>\n<meta property=\"og:description\" content=\"Letztendlich wird das Risiko erheblich reduziert, und SAP-IT-Teams k\u00f6nnen hochwertige SAP Changes in Gesch\u00e4ftsgeschwindigkeit bereitstellen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rev-trac.com\/de\/artikel\/shift-left-sap-aenderungsrisikos\/\" \/>\n<meta property=\"og:site_name\" content=\"Rev-Trac\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-27T14:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rev-trac.com\/wp-content\/uploads\/manageSAPbeyondCharm2-4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1366\" \/>\n\t<meta property=\"og:image:height\" content=\"780\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Chris Drake\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chris Drake\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/artikel\\\/shift-left-sap-aenderungsrisikos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/artikel\\\/shift-left-sap-aenderungsrisikos\\\/\"},\"author\":{\"name\":\"Chris Drake\",\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/#\\\/schema\\\/person\\\/86713147bb4fe41aeb1c9c26c229a03e\"},\"headline\":\"Shift Left zur einfachen Reduzierung des SAP-\u00c4nderungsrisikos\",\"datePublished\":\"2021-09-27T14:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/artikel\\\/shift-left-sap-aenderungsrisikos\\\/\"},\"wordCount\":770,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/#organization\"},\"keywords\":[\"Risikominderung\"],\"articleSection\":[\"Artikel\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rev-trac.com\\\/de\\\/artikel\\\/shift-left-sap-aenderungsrisikos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/artikel\\\/shift-left-sap-aenderungsrisikos\\\/\",\"url\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/artikel\\\/shift-left-sap-aenderungsrisikos\\\/\",\"name\":\"Shift Left zur einfachen Reduzierung des SAP-\u00c4nderungsrisikos - Rev-Trac\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/#website\"},\"datePublished\":\"2021-09-27T14:00:00+00:00\",\"description\":\"Letztendlich wird das Risiko erheblich reduziert, und SAP-IT-Teams k\u00f6nnen hochwertige SAP Changes in Gesch\u00e4ftsgeschwindigkeit bereitstellen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/artikel\\\/shift-left-sap-aenderungsrisikos\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rev-trac.com\\\/de\\\/artikel\\\/shift-left-sap-aenderungsrisikos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/artikel\\\/shift-left-sap-aenderungsrisikos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shift Left zur einfachen Reduzierung des SAP-\u00c4nderungsrisikos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/\",\"name\":\"Rev-Trac\",\"description\":\"Unifying SAP Change Management\",\"publisher\":{\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/#organization\",\"name\":\"Rev-Trac\",\"url\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rev-trac.com\\\/wp-content\\\/uploads\\\/Brandmark_Colour.png\",\"contentUrl\":\"https:\\\/\\\/rev-trac.com\\\/wp-content\\\/uploads\\\/Brandmark_Colour.png\",\"width\":1000,\"height\":1000,\"caption\":\"Rev-Trac\"},\"image\":{\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"description\":\"Rev-Trac automates SAP change delivery, governs every environment, and gives enterprises the confidence to transform without losing control. Continuous Innovation. Continuous Transformation. Complete Governance.\",\"email\":\"hello@rev-trac.com\",\"foundingDate\":\"1997-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/#\\\/schema\\\/person\\\/86713147bb4fe41aeb1c9c26c229a03e\",\"name\":\"Chris Drake\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be3286ae89b19e43d9be0eb2b8b263d542de0b4c9eddde3196ef7a6d46a32271?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be3286ae89b19e43d9be0eb2b8b263d542de0b4c9eddde3196ef7a6d46a32271?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be3286ae89b19e43d9be0eb2b8b263d542de0b4c9eddde3196ef7a6d46a32271?s=96&d=mm&r=g\",\"caption\":\"Chris Drake\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Shift Left zur einfachen Reduzierung des SAP-\u00c4nderungsrisikos - Rev-Trac","description":"Letztendlich wird das Risiko erheblich reduziert, und SAP-IT-Teams k\u00f6nnen hochwertige SAP Changes in Gesch\u00e4ftsgeschwindigkeit bereitstellen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rev-trac.com\/de\/artikel\/shift-left-sap-aenderungsrisikos\/","og_locale":"de_DE","og_type":"article","og_title":"Shift Left zur einfachen Reduzierung des SAP-\u00c4nderungsrisikos","og_description":"Letztendlich wird das Risiko erheblich reduziert, und SAP-IT-Teams k\u00f6nnen hochwertige SAP Changes in Gesch\u00e4ftsgeschwindigkeit bereitstellen.","og_url":"https:\/\/rev-trac.com\/de\/artikel\/shift-left-sap-aenderungsrisikos\/","og_site_name":"Rev-Trac","article_published_time":"2021-09-27T14:00:00+00:00","og_image":[{"width":1366,"height":780,"url":"https:\/\/rev-trac.com\/wp-content\/uploads\/manageSAPbeyondCharm2-4.png","type":"image\/png"}],"author":"Chris Drake","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Chris Drake","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rev-trac.com\/de\/artikel\/shift-left-sap-aenderungsrisikos\/#article","isPartOf":{"@id":"https:\/\/rev-trac.com\/de\/artikel\/shift-left-sap-aenderungsrisikos\/"},"author":{"name":"Chris Drake","@id":"https:\/\/rev-trac.com\/de\/#\/schema\/person\/86713147bb4fe41aeb1c9c26c229a03e"},"headline":"Shift Left zur einfachen Reduzierung des SAP-\u00c4nderungsrisikos","datePublished":"2021-09-27T14:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/rev-trac.com\/de\/artikel\/shift-left-sap-aenderungsrisikos\/"},"wordCount":770,"commentCount":0,"publisher":{"@id":"https:\/\/rev-trac.com\/de\/#organization"},"keywords":["Risikominderung"],"articleSection":["Artikel"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rev-trac.com\/de\/artikel\/shift-left-sap-aenderungsrisikos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rev-trac.com\/de\/artikel\/shift-left-sap-aenderungsrisikos\/","url":"https:\/\/rev-trac.com\/de\/artikel\/shift-left-sap-aenderungsrisikos\/","name":"Shift Left zur einfachen Reduzierung des SAP-\u00c4nderungsrisikos - Rev-Trac","isPartOf":{"@id":"https:\/\/rev-trac.com\/de\/#website"},"datePublished":"2021-09-27T14:00:00+00:00","description":"Letztendlich wird das Risiko erheblich reduziert, und SAP-IT-Teams k\u00f6nnen hochwertige SAP Changes in Gesch\u00e4ftsgeschwindigkeit bereitstellen.","breadcrumb":{"@id":"https:\/\/rev-trac.com\/de\/artikel\/shift-left-sap-aenderungsrisikos\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rev-trac.com\/de\/artikel\/shift-left-sap-aenderungsrisikos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rev-trac.com\/de\/artikel\/shift-left-sap-aenderungsrisikos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rev-trac.com\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Shift Left zur einfachen Reduzierung des SAP-\u00c4nderungsrisikos"}]},{"@type":"WebSite","@id":"https:\/\/rev-trac.com\/de\/#website","url":"https:\/\/rev-trac.com\/de\/","name":"Rev-Trac","description":"Unifying SAP Change Management","publisher":{"@id":"https:\/\/rev-trac.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rev-trac.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rev-trac.com\/de\/#organization","name":"Rev-Trac","url":"https:\/\/rev-trac.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rev-trac.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/rev-trac.com\/wp-content\/uploads\/Brandmark_Colour.png","contentUrl":"https:\/\/rev-trac.com\/wp-content\/uploads\/Brandmark_Colour.png","width":1000,"height":1000,"caption":"Rev-Trac"},"image":{"@id":"https:\/\/rev-trac.com\/de\/#\/schema\/logo\/image\/"},"description":"Rev-Trac automates SAP change delivery, governs every environment, and gives enterprises the confidence to transform without losing control. Continuous Innovation. Continuous Transformation. Complete Governance.","email":"hello@rev-trac.com","foundingDate":"1997-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}},{"@type":"Person","@id":"https:\/\/rev-trac.com\/de\/#\/schema\/person\/86713147bb4fe41aeb1c9c26c229a03e","name":"Chris Drake","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/be3286ae89b19e43d9be0eb2b8b263d542de0b4c9eddde3196ef7a6d46a32271?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/be3286ae89b19e43d9be0eb2b8b263d542de0b4c9eddde3196ef7a6d46a32271?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/be3286ae89b19e43d9be0eb2b8b263d542de0b4c9eddde3196ef7a6d46a32271?s=96&d=mm&r=g","caption":"Chris Drake"}}]}},"_links":{"self":[{"href":"https:\/\/rev-trac.com\/de\/wp-json\/wp\/v2\/posts\/105736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rev-trac.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rev-trac.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rev-trac.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rev-trac.com\/de\/wp-json\/wp\/v2\/comments?post=105736"}],"version-history":[{"count":0,"href":"https:\/\/rev-trac.com\/de\/wp-json\/wp\/v2\/posts\/105736\/revisions"}],"wp:attachment":[{"href":"https:\/\/rev-trac.com\/de\/wp-json\/wp\/v2\/media?parent=105736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rev-trac.com\/de\/wp-json\/wp\/v2\/categories?post=105736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rev-trac.com\/de\/wp-json\/wp\/v2\/tags?post=105736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}