{"id":105423,"date":"2022-07-07T00:00:00","date_gmt":"2022-07-06T14:00:00","guid":{"rendered":"https:\/\/revtrac2026.tempurl.host\/uncategorized\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\/"},"modified":"2022-07-07T00:00:00","modified_gmt":"2022-07-06T14:00:00","slug":"revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen","status":"publish","type":"post","link":"https:\/\/rev-trac.com\/de\/pressemitteilungen\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\/","title":{"rendered":"Revelation Software Concepts und Cognitus geben strategische Partnerschaft bekannt, um S\/4HANA-Projekte zu vereinfachen"},"content":{"rendered":"<p><strong>Melbourne, Australien \u2013 7. Juli 2022:<\/strong> Revelation Software Concepts (RSC), ein f\u00fchrender Anbieter von SAP-Change-Management- und Intelligence-Software, hat eine neue Partnerschaft mit Cognitus bekannt gegeben, einem SAP-Gold-Partner, der SAP-L\u00f6sungen vertreibt und implementiert, um Unternehmen dabei zu unterst\u00fctzen, in einer digitalen Welt einen Schritt voraus zu sein.<\/p>\n<p>Die Zusammenarbeit hat bereits f\u00fcr mehrere Kunden digitale Herausforderungen gel\u00f6st, darunter Danbury Mission Technologies, das Rev-Trac, RSCs automatisierte SAP-Change-Management-Plattform, eingef\u00fchrt hat, um die erfolgreiche Migration zu S\/4HANA zu unterst\u00fctzen.<\/p>\n<p>Die Partnerschaft zwischen RSC und Cognitus schafft L\u00f6sungen, um die steigende Nachfrage von Unternehmen nach digitaler Transformation zu erf\u00fcllen und ein erstklassiges Kundenerlebnis zu bieten, w\u00e4hrend Innovationen beschleunigt werden. Sie versetzt Unternehmen in die Lage, schneller bessere Gesch\u00e4ftsergebnisse zu erzielen \u2013 mit einer schnellen, risikoreduzierten Migration zu S\/4HANA; den Bausteinen f\u00fcr eine digitale Transformationsstrategie. <\/p>\n<p>Im Rahmen der Partnerschaft kann Cognitus seinen Kunden Rev-Trac als Add-on zu seiner erweiterten Gallop-Produktsuite und SAP-Consulting-Expertise anbieten, um Kunden besser eine planbare Umstellung auf S\/4HANA und die digitale Leistungsf\u00e4higkeit zu erm\u00f6glichen, die erforderlich ist, um mit Innovationen Schritt zu halten.<\/p>\n<p>Daniel Clark, Global Partner Manager f\u00fcr Rev-Trac, sagt, Cognitus sei der perfekte Partner f\u00fcr die Zusammenarbeit bei digitalen Transformationsprojekten.<\/p>\n<blockquote><p>\u201eUnsere automatisierten SAP-Change-Management- und Intelligence-Tools erg\u00e4nzen die S\/4HANA-Paketl\u00f6sungen von Cognitus und erleichtern eine erfolgreiche digitale Transformation heute sowie die Vermeidung von Problemen in der Zukunft.\u201c<\/p><\/blockquote>\n<p>\u201eMit einem Ruf und einer Pr\u00e4senz, die auf dem Erfolg seiner S\/4HANA-Produktsuite in den USA und in EMEA basieren, freuen wir uns darauf, dass unsere Partnerschaft mit Cognitus es Unternehmen erm\u00f6glicht, Ziele der digitalen Transformation schneller sowie mit weniger Aufwand und Risiko zu erreichen\u201c, sagte er.<\/p>\n<p>Rene van de Zanden, VP Sales bei Cognitus, sagte: \u201eWir freuen uns sehr \u00fcber die Partnerschaft mit RSC, um die digitalen Transformationsprojekte unserer Kunden zu verbessern.\u201c<\/p>\n<p>\u201eRev-Trac st\u00e4rkt unser aktuelles Toolset und erm\u00f6glicht es uns, mehr wertsch\u00f6pfende Services anzubieten.\u201c sagte Herr Steve Brown, Lead SAP Basis Consultant bei Cognitus. \u201eDie F\u00e4higkeit, SAP Change Management zu automatisieren und durchzusetzen sowie eine End-to-End-DevOps-Plattform zu orchestrieren, wird es uns erm\u00f6glichen, S\/4HANA-Migrationen zu vereinfachen und zu beschleunigen, was f\u00fcr unsere Kunden einen zus\u00e4tzlichen Mehrwert und bessere Gesch\u00e4ftsergebnisse bedeutet.\u201c  <\/p>\n<p>\u201eRSC verf\u00fcgt \u00fcber mehr als 20 Jahre Erfahrung darin, Unternehmen zu bef\u00e4higen, schnelle, risikoarme SAP-Changes umzusetzen. Damit sind sie ein idealer Partner, um unsere Kunden bei der sicheren Umstellung auf S\/4HANA zu unterst\u00fctzen und unn\u00f6tige Kosten sowie Projektverz\u00f6gerungen zu vermeiden.\u201c<\/p>\n<p>\u201eWir freuen uns darauf, mit RSC zusammenzuarbeiten, w\u00e4hrend wir weiterhin Herausforderungen auf dem Weg eines Unternehmens zur Digital-First-Organisation l\u00f6sen\u201c, sagte er.<\/p>\n<p><strong>\u00dcber Cognitus <\/strong><\/p>\n<p>Cognitus Consulting ist ein SAP Gold Partner, der SAP-L\u00f6sungen implementiert, bereitstellt, verkauft und unterst\u00fctzt und zudem Apps im SAP-\u00d6kosystem entwickelt \u2013 \u00fcber sein globales Netzwerk von Standorten in Nordamerika, Asien, Lateinamerika und Europa. Mit seinem Gallop-Portfolio, das sich auf S\/4HANA-Assessments, werksseitig gelieferte Migrationen und gef\u00fchrte Ergebnisse f\u00fcr spezifische Verbesserungen von Gesch\u00e4ftsprozessen konzentriert, ist das Unternehmen weltweit f\u00fchrend in der S\/4HANA Movement. <\/p>\n<p>Weitere Informationen finden Sie unter <a href=\"http:\/\/www.cognitus.com\">www.cognitus.com<\/a> oder kontaktieren Sie <a href=\"mailto:sales@cognitusconsulting.com\">sales@cognitusconsulting.com<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Revelation Software Concepts kooperiert mit Cognitus, einem globalen Unternehmen, das auf SAP-Paketl\u00f6sungen spezialisiert ist, um die S\/4HANA-Migration f\u00fcr die digitale Transformation zu beschleunigen.<\/p>\n","protected":false},"author":17,"featured_media":108080,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"demo_duration":"","demo_product":"","demo_audience":"","demo_integrations":"","demo_url":"","demo_lede":"","webinar_type":"","webinar_status":"","webinar_date_display":"","webinar_date_start":"","webinar_time":"","webinar_duration":"","webinar_platform":"","webinar_presenter":"","webinar_video":"","agenda1_title":"","agenda1_desc":"","agenda2_title":"","agenda2_desc":"","agenda3_title":"","agenda3_desc":"","agenda4_title":"","agenda4_desc":"","agenda5_title":"","agenda5_desc":"","speaker1_name":"","speaker1_role":"","speaker1_photo":"","speaker2_name":"","speaker2_role":"","speaker2_photo":"","speaker3_name":"","speaker3_role":"","speaker3_photo":"","speaker4_name":"","speaker4_role":"","speaker4_photo":"","webinar_register":"","event_status":"","event_date_display":"","event_date_start":"","event_location":"","event_booth":"","event_format":"","event_url":"","session1_title":"","session1_speaker":"","session1_when":"","session1_room":"","session2_title":"","session2_speaker":"","session2_when":"","session2_room":"","session3_title":"","session3_speaker":"","session3_when":"","session3_room":"","session4_title":"","session4_speaker":"","session4_when":"","session4_room":"","team1_name":"","team1_role":"","team1_photo":"","team1_email":"","team1_linkedin":"","team2_name":"","team2_role":"","team2_photo":"","team2_email":"","team2_linkedin":"","team3_name":"","team3_role":"","team3_photo":"","team3_email":"","team3_linkedin":"","team4_name":"","team4_role":"","team4_photo":"","team4_email":"","team4_linkedin":"","team5_name":"","team5_role":"","team5_photo":"","team5_email":"","team5_linkedin":"","team6_name":"","team6_role":"","team6_photo":"","team6_email":"","team6_linkedin":"","event_booking":"","event_lede":"","cs_stat1_label":"","cs_stat1_value":"","cs_stat1_unit":"","cs_stat1_desc":"","cs_stat2_label":"","cs_stat2_value":"","cs_stat2_unit":"","cs_stat2_desc":"","cs_stat3_label":"","cs_stat3_value":"","cs_stat3_unit":"","cs_stat3_desc":"","cs_stat4_label":"","cs_stat4_value":"","cs_stat4_unit":"","cs_stat4_desc":"","cs_download_url":"","page_builder":"","footnotes":""},"categories":[172],"tags":[494],"class_list":["post-105423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pressemitteilungen","tag-release-managements-4hana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Revelation Software Concepts und Cognitus geben strategische Partnerschaft bekannt, um S\/4HANA-Projekte zu vereinfachen - Rev-Trac<\/title>\n<meta name=\"description\" content=\"Revelation Software Concepts kooperiert mit Cognitus, einem globalen Unternehmen, das auf SAP-Paketl\u00f6sungen spezialisiert ist, um die S\/4HANA-Migration f\u00fcr die digitale Transformation zu beschleunigen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rev-trac.com\/de\/pressemitteilungen\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Revelation Software Concepts und Cognitus geben strategische Partnerschaft bekannt, um S\/4HANA-Projekte zu vereinfachen\" \/>\n<meta property=\"og:description\" content=\"Revelation Software Concepts kooperiert mit Cognitus, einem globalen Unternehmen, das auf SAP-Paketl\u00f6sungen spezialisiert ist, um die S\/4HANA-Migration f\u00fcr die digitale Transformation zu beschleunigen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rev-trac.com\/de\/pressemitteilungen\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\/\" \/>\n<meta property=\"og:site_name\" content=\"Rev-Trac\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-06T14:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rev-trac.com\/wp-content\/uploads\/RSC-Cognitus-Partnership.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"621\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Rev-Trac\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rev-Trac\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/pressemitteilungen\\\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/pressemitteilungen\\\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\\\/\"},\"author\":{\"name\":\"Rev-Trac\",\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/#\\\/schema\\\/person\\\/9b28ad7bd22317cc32691221e4164ead\"},\"headline\":\"Revelation Software Concepts und Cognitus geben strategische Partnerschaft bekannt, um S\\\/4HANA-Projekte zu vereinfachen\",\"datePublished\":\"2022-07-06T14:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/pressemitteilungen\\\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\\\/\"},\"wordCount\":541,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/pressemitteilungen\\\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rev-trac.com\\\/wp-content\\\/uploads\\\/RSC-Cognitus-Partnership.png\",\"keywords\":[\"Release management|s\\\/4hana\"],\"articleSection\":[\"Pressemitteilungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rev-trac.com\\\/de\\\/pressemitteilungen\\\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/pressemitteilungen\\\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\\\/\",\"url\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/pressemitteilungen\\\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\\\/\",\"name\":\"Revelation Software Concepts und Cognitus geben strategische Partnerschaft bekannt, um S\\\/4HANA-Projekte zu vereinfachen - Rev-Trac\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/pressemitteilungen\\\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/pressemitteilungen\\\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rev-trac.com\\\/wp-content\\\/uploads\\\/RSC-Cognitus-Partnership.png\",\"datePublished\":\"2022-07-06T14:00:00+00:00\",\"description\":\"Revelation Software Concepts kooperiert mit Cognitus, einem globalen Unternehmen, das auf SAP-Paketl\u00f6sungen spezialisiert ist, um die S\\\/4HANA-Migration f\u00fcr die digitale Transformation zu beschleunigen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/pressemitteilungen\\\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rev-trac.com\\\/de\\\/pressemitteilungen\\\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/pressemitteilungen\\\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rev-trac.com\\\/wp-content\\\/uploads\\\/RSC-Cognitus-Partnership.png\",\"contentUrl\":\"https:\\\/\\\/rev-trac.com\\\/wp-content\\\/uploads\\\/RSC-Cognitus-Partnership.png\",\"width\":1280,\"height\":621,\"caption\":\"Revelation Software Concepts and Cognitus Announce Strategic Partnership to Simplify S\\\/4HANA Projects\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/pressemitteilungen\\\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Revelation Software Concepts und Cognitus geben strategische Partnerschaft bekannt, um S\\\/4HANA-Projekte zu vereinfachen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/\",\"name\":\"Rev-Trac\",\"description\":\"Unifying SAP Change Management\",\"publisher\":{\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/#organization\",\"name\":\"Rev-Trac\",\"url\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rev-trac.com\\\/wp-content\\\/uploads\\\/Brandmark_Colour.png\",\"contentUrl\":\"https:\\\/\\\/rev-trac.com\\\/wp-content\\\/uploads\\\/Brandmark_Colour.png\",\"width\":1000,\"height\":1000,\"caption\":\"Rev-Trac\"},\"image\":{\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"description\":\"Rev-Trac automates SAP change delivery, governs every environment, and gives enterprises the confidence to transform without losing control. Continuous Innovation. Continuous Transformation. Complete Governance.\",\"email\":\"hello@rev-trac.com\",\"foundingDate\":\"1997-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rev-trac.com\\\/de\\\/#\\\/schema\\\/person\\\/9b28ad7bd22317cc32691221e4164ead\",\"name\":\"Rev-Trac\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/344b59f7f26555af480b7d4f1602cd4e2de57b72e77017c0a2de9176498f7984?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/344b59f7f26555af480b7d4f1602cd4e2de57b72e77017c0a2de9176498f7984?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/344b59f7f26555af480b7d4f1602cd4e2de57b72e77017c0a2de9176498f7984?s=96&d=mm&r=g\",\"caption\":\"Rev-Trac\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Revelation Software Concepts und Cognitus geben strategische Partnerschaft bekannt, um S\/4HANA-Projekte zu vereinfachen - Rev-Trac","description":"Revelation Software Concepts kooperiert mit Cognitus, einem globalen Unternehmen, das auf SAP-Paketl\u00f6sungen spezialisiert ist, um die S\/4HANA-Migration f\u00fcr die digitale Transformation zu beschleunigen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rev-trac.com\/de\/pressemitteilungen\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\/","og_locale":"de_DE","og_type":"article","og_title":"Revelation Software Concepts und Cognitus geben strategische Partnerschaft bekannt, um S\/4HANA-Projekte zu vereinfachen","og_description":"Revelation Software Concepts kooperiert mit Cognitus, einem globalen Unternehmen, das auf SAP-Paketl\u00f6sungen spezialisiert ist, um die S\/4HANA-Migration f\u00fcr die digitale Transformation zu beschleunigen.","og_url":"https:\/\/rev-trac.com\/de\/pressemitteilungen\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\/","og_site_name":"Rev-Trac","article_published_time":"2022-07-06T14:00:00+00:00","og_image":[{"width":1280,"height":621,"url":"https:\/\/rev-trac.com\/wp-content\/uploads\/RSC-Cognitus-Partnership.png","type":"image\/png"}],"author":"Rev-Trac","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Rev-Trac","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rev-trac.com\/de\/pressemitteilungen\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\/#article","isPartOf":{"@id":"https:\/\/rev-trac.com\/de\/pressemitteilungen\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\/"},"author":{"name":"Rev-Trac","@id":"https:\/\/rev-trac.com\/de\/#\/schema\/person\/9b28ad7bd22317cc32691221e4164ead"},"headline":"Revelation Software Concepts und Cognitus geben strategische Partnerschaft bekannt, um S\/4HANA-Projekte zu vereinfachen","datePublished":"2022-07-06T14:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/rev-trac.com\/de\/pressemitteilungen\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\/"},"wordCount":541,"commentCount":0,"publisher":{"@id":"https:\/\/rev-trac.com\/de\/#organization"},"image":{"@id":"https:\/\/rev-trac.com\/de\/pressemitteilungen\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\/#primaryimage"},"thumbnailUrl":"https:\/\/rev-trac.com\/wp-content\/uploads\/RSC-Cognitus-Partnership.png","keywords":["Release management|s\/4hana"],"articleSection":["Pressemitteilungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rev-trac.com\/de\/pressemitteilungen\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rev-trac.com\/de\/pressemitteilungen\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\/","url":"https:\/\/rev-trac.com\/de\/pressemitteilungen\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\/","name":"Revelation Software Concepts und Cognitus geben strategische Partnerschaft bekannt, um S\/4HANA-Projekte zu vereinfachen - Rev-Trac","isPartOf":{"@id":"https:\/\/rev-trac.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rev-trac.com\/de\/pressemitteilungen\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\/#primaryimage"},"image":{"@id":"https:\/\/rev-trac.com\/de\/pressemitteilungen\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\/#primaryimage"},"thumbnailUrl":"https:\/\/rev-trac.com\/wp-content\/uploads\/RSC-Cognitus-Partnership.png","datePublished":"2022-07-06T14:00:00+00:00","description":"Revelation Software Concepts kooperiert mit Cognitus, einem globalen Unternehmen, das auf SAP-Paketl\u00f6sungen spezialisiert ist, um die S\/4HANA-Migration f\u00fcr die digitale Transformation zu beschleunigen.","breadcrumb":{"@id":"https:\/\/rev-trac.com\/de\/pressemitteilungen\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rev-trac.com\/de\/pressemitteilungen\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rev-trac.com\/de\/pressemitteilungen\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\/#primaryimage","url":"https:\/\/rev-trac.com\/wp-content\/uploads\/RSC-Cognitus-Partnership.png","contentUrl":"https:\/\/rev-trac.com\/wp-content\/uploads\/RSC-Cognitus-Partnership.png","width":1280,"height":621,"caption":"Revelation Software Concepts and Cognitus Announce Strategic Partnership to Simplify S\/4HANA Projects"},{"@type":"BreadcrumbList","@id":"https:\/\/rev-trac.com\/de\/pressemitteilungen\/revelation-software-concepts-und-cognitus-geben-strategische-partnerschaft-bekannt-um-s-4hana-projekte-zu-vereinfachen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rev-trac.com\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Revelation Software Concepts und Cognitus geben strategische Partnerschaft bekannt, um S\/4HANA-Projekte zu vereinfachen"}]},{"@type":"WebSite","@id":"https:\/\/rev-trac.com\/de\/#website","url":"https:\/\/rev-trac.com\/de\/","name":"Rev-Trac","description":"Unifying SAP Change Management","publisher":{"@id":"https:\/\/rev-trac.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rev-trac.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rev-trac.com\/de\/#organization","name":"Rev-Trac","url":"https:\/\/rev-trac.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rev-trac.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/rev-trac.com\/wp-content\/uploads\/Brandmark_Colour.png","contentUrl":"https:\/\/rev-trac.com\/wp-content\/uploads\/Brandmark_Colour.png","width":1000,"height":1000,"caption":"Rev-Trac"},"image":{"@id":"https:\/\/rev-trac.com\/de\/#\/schema\/logo\/image\/"},"description":"Rev-Trac automates SAP change delivery, governs every environment, and gives enterprises the confidence to transform without losing control. Continuous Innovation. Continuous Transformation. Complete Governance.","email":"hello@rev-trac.com","foundingDate":"1997-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}},{"@type":"Person","@id":"https:\/\/rev-trac.com\/de\/#\/schema\/person\/9b28ad7bd22317cc32691221e4164ead","name":"Rev-Trac","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/344b59f7f26555af480b7d4f1602cd4e2de57b72e77017c0a2de9176498f7984?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/344b59f7f26555af480b7d4f1602cd4e2de57b72e77017c0a2de9176498f7984?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/344b59f7f26555af480b7d4f1602cd4e2de57b72e77017c0a2de9176498f7984?s=96&d=mm&r=g","caption":"Rev-Trac"}}]}},"_links":{"self":[{"href":"https:\/\/rev-trac.com\/de\/wp-json\/wp\/v2\/posts\/105423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rev-trac.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rev-trac.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rev-trac.com\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/rev-trac.com\/de\/wp-json\/wp\/v2\/comments?post=105423"}],"version-history":[{"count":0,"href":"https:\/\/rev-trac.com\/de\/wp-json\/wp\/v2\/posts\/105423\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rev-trac.com\/de\/wp-json\/wp\/v2\/media\/108080"}],"wp:attachment":[{"href":"https:\/\/rev-trac.com\/de\/wp-json\/wp\/v2\/media?parent=105423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rev-trac.com\/de\/wp-json\/wp\/v2\/categories?post=105423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rev-trac.com\/de\/wp-json\/wp\/v2\/tags?post=105423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}